{"id":174,"date":"2013-03-15T13:24:01","date_gmt":"2013-03-15T16:24:01","guid":{"rendered":"http:\/\/www.jeremiaspalazzesi.com.ar\/blog\/?p=174"},"modified":"2013-03-18T13:15:20","modified_gmt":"2013-03-18T16:15:20","slug":"it-e-imagen-corporativa","status":"publish","type":"post","link":"https:\/\/www.nerdadas.com\/blog\/it-e-imagen-corporativa\/","title":{"rendered":"IT e Imagen Corporativa"},"content":{"rendered":"<p>As\u00ed c\u00f3mo de la nada, en la mesa de un bar mi amigo, en informal charla de amigos,\u00a0 se puso a comentar que<strong> la empresa d\u00f3nde trabaja ahora, es muy seria<\/strong>. Si si, una empresa seria en Argentina. Famosa multinacional pero que trata como \u00abPersonas\u00bb reales a sus empleados. Me mat\u00f3, super groso. As\u00ed como la pint\u00f3 ya me quer\u00eda ir a trabajar ah\u00ed. S\u00f3lo con esa presentaci\u00f3n (Aaaa, adem\u00e1s coment\u00f3 que tiene muy buenos sueldos, eso ayud\u00f3).<\/p>\n<p>De todas formas prosigui\u00f3 cont\u00e1ndonos de dicha empresa y se detuvo en los detalles. Los detalles en los que not\u00f3 la seriedad de la misma. Y ahi&#8230; se\u00f1ores y se\u00f1oras&#8230; es d\u00f3nde lleg\u00f3 a mi mente la sacudida.<\/p>\n<p>Una de las cosas sencillas fu\u00e9&#8230; \u00abPara tal fecha especial arrancamos el d\u00eda con un fondo de pantalla que nos recordaba eso mismo\u00bb.<\/p>\n<p>Es increible la sencill\u00e9z con la que se llega al coraz\u00f3n del usuario. Por eso me refiero al IT c\u00f3mo parte de la identidad corporativa. Cambiando un fondo de pantalla uno logro demostrarle al usuario que esa pc, que su trabajo es parte integral de la empresa; y traslad\u00f3 al puesto de trabajo la identidad corporativa. Ese usuario ahora es una mano, un dedo\u00a0 un pi\u00e9 de la organizaci\u00f3n. Otro detalle fundamental es demostrarle tambi\u00e9n al usuario que la empresa tiene control total de los activos del equipo, mostrando tambi\u00e9n cierta autoridad tal. (Uno lo pensar\u00eda dos veces antes de bajar la \u00faltima parte del video de Florencia Pe\u00f1a)<\/p>\n<figure id=\"attachment_175\" aria-describedby=\"caption-attachment-175\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.jeremiaspalazzesi.com.ar\/blog\/wp-content\/uploads\/2013\/03\/comunicacion-corporativa1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-175 \" alt=\"IT e Imagen Corporativa\" src=\"http:\/\/www.jeremiaspalazzesi.com.ar\/blog\/wp-content\/uploads\/2013\/03\/comunicacion-corporativa1-300x225.jpg\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.nerdadas.com\/blog\/wp-content\/uploads\/2013\/03\/comunicacion-corporativa1-300x225.jpg 300w, https:\/\/www.nerdadas.com\/blog\/wp-content\/uploads\/2013\/03\/comunicacion-corporativa1-1024x768.jpg 1024w, https:\/\/www.nerdadas.com\/blog\/wp-content\/uploads\/2013\/03\/comunicacion-corporativa1-160x120.jpg 160w, https:\/\/www.nerdadas.com\/blog\/wp-content\/uploads\/2013\/03\/comunicacion-corporativa1.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-175\" class=\"wp-caption-text\">Six Points!<\/figcaption><\/figure>\n<p>Ante esto se me ocurrieron algunos Tips para implementar en la organizaci\u00f3n desde el departamento de IT para mostrar una imagen corporativa fuerte en la empresa.<\/p>\n<ol>\n<li><em>Obviamente la primera es el fondo de Pantalla \u00abcorporativo\u00bb. Tanto en Linux como en Windows se puede aplicar si el login est\u00e1 centralizado en muy pocos pasos.<\/em><br \/>\n<em>En Windows, con Active Directory s\u00f3lo hay que aplicar\u00a0 una pol\u00edtica que cambie el fondo de pantalla actual. Es muy sencillo\u00a0 y ya dar\u00e9 tips para lograrlo en pr\u00f3ximos art\u00edculos. Tambi\u00e9n es factible y mucho m\u00e1s sencillo cu\u00e1ndo se usan clientes delgados o RDP (Terminal Service o Escritorio Remoto), s\u00f3lo se modifica localmente el perfil del usuario. En Linux, con Thin Client es igual, es local. (Siempre est\u00e1 google para aclarar m\u00e1s dudas)<\/em><\/li>\n<li><em>La Firma. Si hay algo que hace sentir la fuerza de la empresa es la firma corporativa. Toda la empresa con la misma firma pero personalizada con los datos de qui\u00e9n corresponde. Es importante que la firma se administre centralmente en la oficina IT y lograr que todos los puestos tengan la misma con el mismo dise\u00f1o (Tama\u00f1o, logos, fuentes) a fin de fortalecer la idea. Los datos a incluir los deber\u00eda cargar el mismo usuario.<\/em><\/li>\n<li><em>Esto no es parte de IT exclusivamente pero en la medida de lo posible cada PC, Notebook, Pendrive, Mouse, Disco o Pad deber\u00edan salir con una calco impresa de la compa\u00f1\u00eda (U otro m\u00e9todo de identificaci\u00f3n). Esto no evitar\u00eda los robos pero si mostrar\u00eda que es equipo de la empresa y como tal debe cuidarse. El mouse, el pad, los monitores&#8230; quizas no, pero si las notebooks y PCs. C\u00f3mo medida para agregar (algo que resolvimos hacer hace mucho por mis lares) pegar en dicha pc datos de configuraci\u00f3n \u00fanicos. Por ejemplo la IP sino es din\u00e1mica o el nombre del equipo, para evitar malentendidos. Un n\u00famero de serie de inventario tampoco es mala idea.<\/em><\/li>\n<li><em><\/em><em>Acceso remoto (Gerentes o trabajadores a distancia) desde cualquier lado a su escritorio tambi\u00e9n es una buena pol\u00edtica de im\u00e1gen. \u00abMi empresa est\u00e1 en todos lados\u00bb Pero guarda con la seguridad!. Muuucho cuidado. Implentar certificados, VPN robustas (Nada de andar jugando con PPTP si existe OpenVPN o Juniper Network. A encriptar discos y poner accesos con claves. Fundamentalmente.<\/em>\n<p><figure id=\"attachment_176\" aria-describedby=\"caption-attachment-176\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.jeremiaspalazzesi.com.ar\/blog\/wp-content\/uploads\/2013\/03\/shutterstock_24035878.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-176\" title=\"Construyendo Empresas\" alt=\"Construyendo Empresas\" src=\"http:\/\/www.jeremiaspalazzesi.com.ar\/blog\/wp-content\/uploads\/2013\/03\/shutterstock_24035878-300x200.jpg\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.nerdadas.com\/blog\/wp-content\/uploads\/2013\/03\/shutterstock_24035878-300x200.jpg 300w, https:\/\/www.nerdadas.com\/blog\/wp-content\/uploads\/2013\/03\/shutterstock_24035878-1024x685.jpg 1024w, https:\/\/www.nerdadas.com\/blog\/wp-content\/uploads\/2013\/03\/shutterstock_24035878-120x80.jpg 120w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-176\" class=\"wp-caption-text\">Construyendo Empresas<\/figcaption><\/figure><\/li>\n<li><em>Proxy&#8217;s personalizados. No dejen la p\u00e1gina de \u00abACCESO DENEGADO!\u00bb de Squid. Armens\u00e9 algo como la gente, con logotivo y todo. The Big Brother se los agradecer\u00e1!.<\/em><\/li>\n<li><em>Accesos SSH con Bienvenidas!. Un detalle, pero como vendeeee!!!. Remplacen el archivo MOTD en Linux con el nombre de la empresa en ascii (http:\/\/www.network-science.de\/ascii\/). Obvio, s\u00f3lo si tienen aplicaciones corriendo que vean sus usuarios internos. NO RECOMIENDO PARA ACCESOS EXTERNOS!. Le estar\u00edan dando una motivaci\u00f3n extra al Hacker (o Script Kiddie) de turno.<\/em><\/li>\n<li><em>Tarjetas de Acceso con logotipos. Todos los accesos que puedan restrinjan con tarjetas, RFID o Huellas. La empresa es segura.<\/em><\/li>\n<li><em>Smartphones. Fondos de pantalla y agenda corporativa para todo el mundo. (Parezco el pol\u00edtico de turno).\u00a0 Con clave, por supuesto, y backups en la medida de lo posible.<\/em><\/li>\n<li><em>Y por supuesto, no dejen de mostrar que a los de IT le preocupa el usuario. Muestrens\u00e9, programen mantenimientos mensuales (Y haganl\u00f3s a conciencia) para que vean que aqu\u00ed se trabaja! ( \ud83d\ude42 ).<\/em><\/li>\n<\/ol>\n<p>Terminar\u00e9 este art\u00edculo y se me ocurriran muchas m\u00e1s ideas pero aqu\u00ed estar\u00e9 para contarsel\u00e1s.<\/p>\n<p>La imagen lo es todo. <strong>Usuarios con\u00a0 una PC que funcione a vapor pero con monitor LCD se sienten Hackers de la NSA. Mimen la red.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed c\u00f3mo de la nada, en la mesa de un bar mi amigo, en informal charla de amigos,\u00a0 se puso a comentar que la empresa d\u00f3nde trabaja ahora, es muy seria. Si si, una empresa seria en Argentina. Famosa multinacional pero que trata como \u00abPersonas\u00bb reales a sus empleados. Me mat\u00f3, super groso. As\u00ed como [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":175,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,167,17],"tags":[224,233,234,228,229,217,230,225,226,218,210,216,220,241,219,242,232,240,223,237,869,231,238,221,222,227,235,236,239],"class_list":["post-174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ideas","category-psicologia","category-tecnologia","tag-active","tag-admin","tag-administrador","tag-client","tag-cliente","tag-corporativa","tag-delgado","tag-directory","tag-dominio","tag-empresa","tag-hacker","tag-imagen","tag-it","tag-juniper","tag-negocio","tag-network","tag-oficina","tag-openvpn","tag-red","tag-remotos","tag-seguridad","tag-sistemas","tag-smartphones","tag-soporte","tag-tecnico","tag-thin","tag-usuario","tag-usuarios","tag-vpn"],"_links":{"self":[{"href":"https:\/\/www.nerdadas.com\/blog\/wp-json\/wp\/v2\/posts\/174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nerdadas.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nerdadas.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nerdadas.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nerdadas.com\/blog\/wp-json\/wp\/v2\/comments?post=174"}],"version-history":[{"count":4,"href":"https:\/\/www.nerdadas.com\/blog\/wp-json\/wp\/v2\/posts\/174\/revisions"}],"predecessor-version":[{"id":189,"href":"https:\/\/www.nerdadas.com\/blog\/wp-json\/wp\/v2\/posts\/174\/revisions\/189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nerdadas.com\/blog\/wp-json\/wp\/v2\/media\/175"}],"wp:attachment":[{"href":"https:\/\/www.nerdadas.com\/blog\/wp-json\/wp\/v2\/media?parent=174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nerdadas.com\/blog\/wp-json\/wp\/v2\/categories?post=174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nerdadas.com\/blog\/wp-json\/wp\/v2\/tags?post=174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}